{"id":356,"count":1,"description":"","link":"https:\/\/www.ameriglide.com\/blog\/tag\/grill-safety\/","name":"grill safety","slug":"grill-safety","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>grill safety Archives - AmeriGlide Blog<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.ameriglide.com\/blog\/tag\/grill-safety\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"grill safety Archives - AmeriGlide Blog\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.ameriglide.com\/blog\/tag\/grill-safety\/\" \/>\n<meta property=\"og:site_name\" content=\"AmeriGlide Blog\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ameriglide.com\/blog\/wp-content\/uploads\/2021\/04\/AMG-Logo.png\" \/>\n\t<meta property=\"og:image:width\" content=\"716\" \/>\n\t<meta property=\"og:image:height\" content=\"267\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@ameriglide\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.ameriglide.com\\\/blog\\\/tag\\\/grill-safety\\\/\",\"url\":\"https:\\\/\\\/www.ameriglide.com\\\/blog\\\/tag\\\/grill-safety\\\/\",\"name\":\"grill safety Archives - AmeriGlide Blog\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.ameriglide.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.ameriglide.com\\\/blog\\\/tag\\\/grill-safety\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.ameriglide.com\\\/blog\\\/tag\\\/grill-safety\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Blog\",\"item\":\"https:\\\/\\\/www.ameriglide.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"grill safety\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.ameriglide.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.ameriglide.com\\\/blog\\\/\",\"name\":\"AmeriGlide Blog\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.ameriglide.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"grill safety Archives - AmeriGlide Blog","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.ameriglide.com\/blog\/tag\/grill-safety\/","og_locale":"en_US","og_type":"article","og_title":"grill safety Archives - AmeriGlide Blog","og_url":"https:\/\/www.ameriglide.com\/blog\/tag\/grill-safety\/","og_site_name":"AmeriGlide Blog","og_image":[{"width":716,"height":267,"url":"https:\/\/www.ameriglide.com\/blog\/wp-content\/uploads\/2021\/04\/AMG-Logo.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@ameriglide","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.ameriglide.com\/blog\/tag\/grill-safety\/","url":"https:\/\/www.ameriglide.com\/blog\/tag\/grill-safety\/","name":"grill safety Archives - AmeriGlide Blog","isPartOf":{"@id":"https:\/\/www.ameriglide.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.ameriglide.com\/blog\/tag\/grill-safety\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.ameriglide.com\/blog\/tag\/grill-safety\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Blog","item":"https:\/\/www.ameriglide.com\/blog\/"},{"@type":"ListItem","position":2,"name":"grill safety"}]},{"@type":"WebSite","@id":"https:\/\/www.ameriglide.com\/blog\/#website","url":"https:\/\/www.ameriglide.com\/blog\/","name":"AmeriGlide Blog","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.ameriglide.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.ameriglide.com\/blog\/wp-json\/wp\/v2\/tags\/356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ameriglide.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.ameriglide.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.ameriglide.com\/blog\/wp-json\/wp\/v2\/posts?tags=356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}